{"id":903,"date":"2016-11-16T17:28:01","date_gmt":"2016-11-16T16:28:01","guid":{"rendered":"http:\/\/www.kreativzimmer.net\/kreativzimmer\/?p=903"},"modified":"2017-06-27T12:36:31","modified_gmt":"2017-06-27T10:36:31","slug":"fliegen-mit-kleinkind-welcome-to-sri-lanka","status":"publish","type":"post","link":"http:\/\/www.kreativzimmer.net\/kreativzimmer\/index.php\/2016\/11\/16\/fliegen-mit-kleinkind-welcome-to-sri-lanka\/","title":{"rendered":"Fliegen mit Kleinkind, welcome to Sri Lanka!"},"content":{"rendered":"<p style=\"text-align: justify;\">M\u00fcnchen &#8211; Doha &#8211; Colombo<\/p>\n<blockquote>\n<p style=\"text-align: justify;\">Wenn man manchen Skeptiker glauben schenkt, dann fliegt man im besten Fall niemals mit einem Kleinkind und schon gar nicht eine Fernstrecke!<br \/>\nWir haben haben Beides gewagt, getreu den Motto, dass man nur etwas wirklich beurteilen kann, wenn man es selbst versucht hat. &nbsp;<\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\">Gestartet sind wir vom Flughafen M\u00fcnchen mit einem vollgepackten Backpack, einem kleinen Rucksack als Handgep\u00e4ck und einem Turnbeutel f\u00fcr diverse Artikel, die immer schnell gebraucht werden. Die kleinste Backpackerin haben wir stets im Tragetuch transportiert. Wir entschieden uns f\u00fcr einen Nachtflug, der von M\u00fcnchen aus in zwei F\u00fcnf-Stunden-Etappen mit einem Zwischenstopp von zweieinhalb Stunden in Doha nach Colombo f\u00fchrte.<\/p>\n<p style=\"text-align: justify;\">Vor dem Abflug war unsere Weltenbummlerin durchweg gut besch\u00e4ftigt mit Flugzeuge anschauen und mit den Flugbegleitern zu flirten.<\/p>\n<p style=\"text-align: justify;\">Im Flugzeug selbst hatten wir richtig Gl\u00fcck: zum einen bekamen wir unsere gew\u00fcnschten Pl\u00e4tze in den vorderen Reihen mit Baby K\u00f6rbchen und zum andere war die Maschine nagelneu. Dank unserer s\u00fc\u00dfen Mitreisenden hatten wir auch immer einen bevorzugten Draht zur Crew und wurden w\u00e4hrend des gesamten Fluges bestens umsorgt. Die kleine Backpackerin zieht die Stewardessen scheinbar magisch an.<br \/>\nNach dem Abendessen konnte unsere Tochter entspannt in dem daf\u00fcr vorgesehenen Korb schlafen. Das Abendessen f\u00fcr sie bestand aus Br\u00f6tchen unseres Men\u00fcs, sowie dem von der Airline zur Verf\u00fcgung gestellten Obstgl\u00e4schen. Da unsere Kleine praktisch alles isst war sie so auch sehr gut satt.<br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-907 alignleft\" src=\"http:\/\/www.kreativzimmer.net\/kreativzimmer\/wp-content\/uploads\/2016\/11\/20161114_174531_resized-300x225.jpg\" alt=\"20161114_174531_resized\" width=\"300\" height=\"225\" srcset=\"http:\/\/www.kreativzimmer.net\/kreativzimmer\/wp-content\/uploads\/2016\/11\/20161114_174531_resized-300x225.jpg 300w, http:\/\/www.kreativzimmer.net\/kreativzimmer\/wp-content\/uploads\/2016\/11\/20161114_174531_resized-600x450.jpg 600w, http:\/\/www.kreativzimmer.net\/kreativzimmer\/wp-content\/uploads\/2016\/11\/20161114_174531_resized-768x576.jpg 768w, http:\/\/www.kreativzimmer.net\/kreativzimmer\/wp-content\/uploads\/2016\/11\/20161114_174531_resized-1024x768.jpg 1024w, http:\/\/www.kreativzimmer.net\/kreativzimmer\/wp-content\/uploads\/2016\/11\/20161114_174531_resized-350x263.jpg 350w, http:\/\/www.kreativzimmer.net\/kreativzimmer\/wp-content\/uploads\/2016\/11\/20161114_174531_resized-830x623.jpg 830w, http:\/\/www.kreativzimmer.net\/kreativzimmer\/wp-content\/uploads\/2016\/11\/20161114_174531_resized-230x173.jpg 230w, http:\/\/www.kreativzimmer.net\/kreativzimmer\/wp-content\/uploads\/2016\/11\/20161114_174531_resized-480x360.jpg 480w, http:\/\/www.kreativzimmer.net\/kreativzimmer\/wp-content\/uploads\/2016\/11\/20161114_174531_resized.jpg 1632w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Das Baby Bassinet ist laut daneben angebrachtem Schild bis 15 kg zugelassen, wobei wir fast nicht glauben konnten, dass dort auch \u00e4ltere Kinder gut schlafen k\u00f6nnen. Unsere Einj\u00e4hrige war mit 74 cm gef\u00fchlt schon grenzwertig gro\u00df.<br \/>\nLetztlich war die Gr\u00f6\u00dfe aber ausreichend und lediglich beim Umdrehen ist sie immer wieder kurz wach geworden. In der Zwischenzeit konnten wir das Multimedia Angebot auskosten \ud83d\ude09<\/p>\n<p style=\"text-align: justify;\">Der Zwischenstopp in Doha war dann viel zu aufregend und an Schlaf war somit nicht zu denken. Im Baby Bassinet ist sie dann aber todm\u00fcde eingeschlafen und schlief dort dann tief und fest bis zur Landung.<\/p>\n<p style=\"text-align: justify;\">Wir raten jedem Fernreisenden ein Baby Bassinet zu reservieren, auch wenn das Kind letztlich zu gro\u00df ist oder nicht darin schl\u00e4ft. So hat man einfach viel mehr Platz vor seinen F\u00fc\u00dfen. Diesen kann man dann mit einem krabbelnden Kind oder dem ganzen Baby-Krims-Krams bef\u00fcllen..<\/p>\n<p style=\"text-align: justify;\">In Sri Lanka angekommenn hat uns der zuvor bestellte Taxifahrer des Hotels vergessen. Aber es war ein leichtes ein Taxi direkt vor dem Flughafen zu heuern, welches zudem noch deutlich g\u00fcnstiger war! Der Fahrer war super nett und hat uns bei tropischen Temperaturen voll klimatisiert in zweieinhalb Stunde nach Beruwela in unser Guesthouse gefahren.<br \/>\nDort mit dem Welcoming Drink, einem Passionsfrucht Smoothie, entspannt eingecheckt und den fehlenden Schlaf nachgeholt. Die 4,5 Stunden Zeitverschiebung hat man unserer Kleinen am ersten Tag durchaus noch angemerkt. Wir haben aber von Anfang an den neuen Tag\/Nacht Rhythmus benutzt und so war nach einer Nacht wieder alles beim Alten!<\/p>\n<p style=\"text-align: justify;\">Alles in allem w\u00fcrden wir es jederzeit wieder so machen! Top Airline &#8211; Qatar Airline -, Top Reiseb\u00fcro &#8211; Th\u00fcrmer Tours -, Top Kind \ud83d\ude09<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00fcnchen &#8211; Doha &#8211; Colombo Wenn man manchen Skeptiker glauben schenkt, dann fliegt man im besten Fall niemals mit einem Kleinkind und schon gar nicht eine Fernstrecke! Wir haben haben Beides gewagt, getreu den Motto, dass man nur etwas wirklich beurteilen kann, wenn man es selbst versucht hat. &nbsp; Gestartet sind wir vom Flughafen M\u00fcnchen [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":906,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[37,5],"tags":[126,130,129,41,40,39],"class_list":["post-903","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sri-lanka","category-zimmeraufreisen","tag-backpacking","tag-backpacking-mit-kind","tag-fliegen-mit-kind","tag-reisen-mit-kind","tag-sri-lanka","tag-zimmeraufreisen"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"http:\/\/www.kreativzimmer.net\/kreativzimmer\/wp-content\/uploads\/2016\/11\/20161114_160327_resized-e1479313788519.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p86gX0-ez","_links":{"self":[{"href":"http:\/\/www.kreativzimmer.net\/kreativzimmer\/index.php\/wp-json\/wp\/v2\/posts\/903","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.kreativzimmer.net\/kreativzimmer\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.kreativzimmer.net\/kreativzimmer\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.kreativzimmer.net\/kreativzimmer\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.kreativzimmer.net\/kreativzimmer\/index.php\/wp-json\/wp\/v2\/comments?post=903"}],"version-history":[{"count":5,"href":"http:\/\/www.kreativzimmer.net\/kreativzimmer\/index.php\/wp-json\/wp\/v2\/posts\/903\/revisions"}],"predecessor-version":[{"id":911,"href":"http:\/\/www.kreativzimmer.net\/kreativzimmer\/index.php\/wp-json\/wp\/v2\/posts\/903\/revisions\/911"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.kreativzimmer.net\/kreativzimmer\/index.php\/wp-json\/wp\/v2\/media\/906"}],"wp:attachment":[{"href":"http:\/\/www.kreativzimmer.net\/kreativzimmer\/index.php\/wp-json\/wp\/v2\/media?parent=903"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.kreativzimmer.net\/kreativzimmer\/index.php\/wp-json\/wp\/v2\/categories?post=903"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.kreativzimmer.net\/kreativzimmer\/index.php\/wp-json\/wp\/v2\/tags?post=903"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}